{"id":947,"count":1,"description":"","link":"https:\/\/jobs.dataaxisnode.com\/nigeria\/tag\/the-stellar-workforce-solutions\/","name":"the Stellar Workforce Solutions","slug":"the-stellar-workforce-solutions","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/jobs.dataaxisnode.com\/nigeria\/wp-json\/wp\/v2\/tags\/947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jobs.dataaxisnode.com\/nigeria\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jobs.dataaxisnode.com\/nigeria\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jobs.dataaxisnode.com\/nigeria\/wp-json\/wp\/v2\/posts?tags=947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}